{"id":7386,"count":1,"description":"","link":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/tag\/safadao-e-termino-do-sao-joao-2017\/","name":"Safad\u00e3o e t\u00e9rmino do S\u00e3o Jo\u00e3o 2017","slug":"safadao-e-termino-do-sao-joao-2017","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/tags\/7386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts?tags=7386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}