{"id":7159,"count":1,"description":"","link":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/tag\/plenaria-do-ppa-sera-realizada-no-bairro-santa-rosa-nesta-quarta-12\/","name":"Plen\u00e1ria do PPA ser\u00e1 realizada no bairro Santa Rosa nesta quarta (12)","slug":"plenaria-do-ppa-sera-realizada-no-bairro-santa-rosa-nesta-quarta-12","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/tags\/7159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts?tags=7159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}