{"id":21607,"count":1,"description":"","link":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/tag\/caruaru-suspende-vacinacao-de-gestantes-com-astrazeneca-fiocurz\/","name":"Caruaru suspende vacina\u00e7\u00e3o de gestantes com AstraZeneca\/ Fiocurz","slug":"caruaru-suspende-vacinacao-de-gestantes-com-astrazeneca-fiocurz","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/tags\/21607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts?tags=21607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}