{"id":92702,"date":"2023-02-06T10:39:14","date_gmt":"2023-02-06T13:39:14","guid":{"rendered":"https:\/\/blogdoedvaldomagalhaes.com.br\/?p=92702"},"modified":"2023-02-06T10:39:15","modified_gmt":"2023-02-06T13:39:15","slug":"hra-inicia-processo-de-implementacao-do-lean-nas-emergencias","status":"publish","type":"post","link":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/2023\/02\/06\/hra-inicia-processo-de-implementacao-do-lean-nas-emergencias\/","title":{"rendered":"HRA inicia processo de implementa\u00e7\u00e3o do Lean nas Emerg\u00eancias"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: initial; font-size: revert;\">O Hospital Regional do Agreste (HRA) recebe, nesta segunda-feira (6) e ter\u00e7a-feira (7), consultores do Programa de Apoio ao Desenvolvimento Institucional do Sistema \u00danico de Sa\u00fade (PROADI-SUS) para o in\u00edcio do processo de implementa\u00e7\u00e3o do projeto Lean nas Emerg\u00eancias. O projeto, subsidiado pelo PROADI-SUS, visa diminuir a superlota\u00e7\u00e3o nos servi\u00e7os de emerg\u00eancia de hospitais p\u00fablicos e filantr\u00f3picos do pa\u00eds.<\/span><\/p>\n<p style=\"text-align: justify;\">Aprovado na fase diagn\u00f3stica, o HRA parte, agora, para a implementa\u00e7\u00e3o de metodologias que objetivam gerenciar de forma mais eficaz os leitos de emerg\u00eancia. O Lean nas Emerg\u00eancias \u00e9 executado de forma colaborativa entre v\u00e1rios hospitais nacionais. No HRA, o projeto vai ser acompanhado por profissionais da Benefic\u00eancia Portuguesa de S\u00e3o Paulo.<\/p>\n<p style=\"text-align: justify;\">\u201cReunimos diretoria, coordenadores m\u00e9dico e de enfermagem, equipe multiprofissional e de servi\u00e7os de apoio de cada setor do hospital para que consigamos a maior efic\u00e1cia poss\u00edvel na implanta\u00e7\u00e3o e execu\u00e7\u00e3o do projeto, visando desafogar os servi\u00e7os na emerg\u00eancia para, assim, oferecer um atendimento mais r\u00e1pido e humanizado \u00e0 principal beneficiada, a popula\u00e7\u00e3o\u201d, explica Gabriel Gomes, enfermeiro e coordenador do N\u00facleo de Educa\u00e7\u00e3o Permanente (NEP).<\/p>\n<p style=\"text-align: justify;\">Sobre o Lean nas Emerg\u00eancias &#8211; O Lean nas Emerg\u00eancias \u00e9 um projeto do Minist\u00e9rio da Sa\u00fade executado de forma colaborativa pelos hospitais Benefic\u00eancia Portuguesa de S\u00e3o Paulo (BP), Moinhos de Vento (HMV) e S\u00edrio-Liban\u00eas (HSL), por meio do Programa de Apoio ao Desenvolvimento Institucional do Sistema \u00danico de Sa\u00fade (PROADI-SUS), com o objetivo de reduzir a superlota\u00e7\u00e3o nas urg\u00eancias e emerg\u00eancias de hospitais p\u00fablicos e filantr\u00f3picos do Brasil.<\/p>\n<p style=\"text-align: justify;\">Foto: Divulga\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Siga o Instagram do Blog @blogdoedvaldomagalhaes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Hospital Regional do Agreste (HRA) recebe, nesta segunda-feira (6) e ter\u00e7a-feira (7), consultores do Programa de Apoio ao Desenvolvimento&hellip;<\/p>\n","protected":false},"author":1,"featured_media":92703,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14120],"tags":[2,19532,3406,26727],"class_list":["post-92702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-blog-do-edvaldo-magalhaes","tag-blog-mais-acessado-e-visualizado-de-caruaru-e-regiao","tag-caruaru","tag-hra-inicia-processo-de-implementacao-do-lean-nas-emergencias"],"_links":{"self":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92702"}],"version-history":[{"count":1,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92702\/revisions"}],"predecessor-version":[{"id":92704,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92702\/revisions\/92704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/media\/92703"}],"wp:attachment":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}