{"id":55297,"date":"2020-05-09T13:51:33","date_gmt":"2020-05-09T16:51:33","guid":{"rendered":"http:\/\/blogdoedvaldomagalhaes.com.br\/?p=55297"},"modified":"2020-05-09T20:48:15","modified_gmt":"2020-05-09T23:48:15","slug":"comeca-a-montagem-do-hospital-de-campanha-no-hmv-em-caruaru","status":"publish","type":"post","link":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/2020\/05\/09\/comeca-a-montagem-do-hospital-de-campanha-no-hmv-em-caruaru\/","title":{"rendered":"Come\u00e7a a montagem do Hospital de Campanha no HMV em Caruaru"},"content":{"rendered":"<p style=\"text-align: justify;\">O Blog do Edvaldo Magalh\u00e3es divulga em primeira m\u00e3o que, a montagem do Hospital de Campanha em Caruaru, no Agreste de Pernambuco, come\u00e7ou nessa sexta-feira (08). O local escolhido foi o estacionamento do Hospital Mestre Vitalino. Primeiro foi feita a limpeza, para receber a estrutura do hospital, que chegou nesta semana.<\/p>\n<p style=\"text-align: justify;\">O Hospital de Campanha, destinado a pacientes com Covid-19, vai receber pacientes com sintomas leves ou moderados da doen\u00e7a, sem a necessidade de terapia intensiva.<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: inherit;\">Al\u00e9m de Caruaru, no Agreste, as cidades de Petrolina e Serra Talhada, no Sert\u00e3o de Pernambuco, receber\u00e3o as novas unidades de sa\u00fade, com<\/span><span style=\"font-size: inherit;\"> investimento de aproximadamente R$ 5 milh\u00f5es, do Governo do Estado. nos tr\u00eas hospitais de campanha. Al\u00e9m disso, a maternidade Brites de Albuquerque, em Olinda, transformada em hospital de refer\u00eancia para Covid-19, passar\u00e1 por uma amplia\u00e7\u00e3o da sua estrutura. Assim, ser\u00e3o ofertadas pelo Estado, no total, 342 novas vagas para pacientes do novo coronav\u00edrus.<\/span><\/p>\n<p style=\"text-align: justify;\">\u201cNosso gabinete de crise voltou a se reunir para analisar as a\u00e7\u00f5es j\u00e1 realizadas e discutir o nosso planejamento para os pr\u00f3ximos dias e semanas. Come\u00e7amos a constru\u00e7\u00e3o de tr\u00eas hospitais de campanha no interior, que v\u00e3o nos ajudar muito no enfrentamento \u00e0 Covid-19. Cada um deles contar\u00e1 com cerca de 100 leitos, refor\u00e7ando a rede estadual j\u00e1 existente em cada regi\u00e3o\u201d, afirmou Paulo C\u00e2mara.<\/p>\n<p style=\"text-align: justify;\">Nas unidades de Olinda e Caruaru os trabalhos j\u00e1 come\u00e7aram. O Brites de Albuquerque ganhar\u00e1 mais 41 leitos, sendo 40 para interna\u00e7\u00e3o cl\u00ednica e um para estabiliza\u00e7\u00e3o de pacientes. No Hospital Mestre Vitalino, sediado em Caruaru, o Governo do Estado vai ofertar 76 leitos de interna\u00e7\u00e3o cl\u00ednica, 26 leitos de tratamento semi-intensivo e dois leitos de estabiliza\u00e7\u00e3o, totalizando 104 novas vagas para v\u00edtimas da pandemia.<\/p>\n<p style=\"text-align: justify;\">Em Serra Talhada, o hospital de campanha come\u00e7ar\u00e1 a ser implantado a partir da pr\u00f3xima segunda-feira (11). A unidade contar\u00e1 com 95 vagas, sendo 72 para interna\u00e7\u00e3o cl\u00ednica e 22 para tratamento semi-intensivo, al\u00e9m de um leito de estabiliza\u00e7\u00e3o de pacientes. J\u00e1 a unidade de Petrolina vai ofertar 74 vagas cl\u00ednicas e 26 para pessoas que necessitam de tratamento semi-intensivo. Tamb\u00e9m haver\u00e1 duas vagas para estabiliza\u00e7\u00e3o, totalizando, efetivamente, 102 vagas espec\u00edficas para tratamento da Covid-19.<\/p>\n<p style=\"text-align: justify;\">\u201cOs pr\u00f3ximos dias ser\u00e3o duros. A Covid-19 tem avan\u00e7ado e precisaremos estar ainda mais firmes para salvar vidas e garantir a sa\u00fade dos pernambucanos e pernambucanas\u201d, refor\u00e7ou o governador, citando uma pesquisa divulgada esta semana pela Unesp que aponta o isolamento social \u2013 promovido at\u00e9 agora com a\u00e7\u00f5es restritivas em Pernambuco, com o apoio de grande parte da popula\u00e7\u00e3o \u2013 como respons\u00e1vel por salvar mais de tr\u00eas mil vidas no Estado. \u201cPor isso, pe\u00e7o mais uma vez que fiquem em casa. O isolamento social \u00e9, seguramente, o melhor instrumento para salvarmos mais vidas\u201d, concluiu Paulo C\u00e2mara.<\/p>\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"878\" height=\"1024\" src=\"http:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2020\/05\/Screenshot_20200509-1350362-878x1024.png\" alt=\"\" class=\"wp-image-55307\" srcset=\"https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2020\/05\/Screenshot_20200509-1350362-878x1024.png 878w, https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2020\/05\/Screenshot_20200509-1350362-257x300.png 257w, https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2020\/05\/Screenshot_20200509-1350362-768x895.png 768w, https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2020\/05\/Screenshot_20200509-1350362.png 1067w\" sizes=\"auto, (max-width: 878px) 100vw, 878px\" \/><figcaption>Blog do Edvaldo Magalh\u00e3es<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O Blog do Edvaldo Magalh\u00e3es divulga em primeira m\u00e3o que, a montagem do Hospital de Campanha em Caruaru, no Agreste&hellip;<\/p>\n","protected":false},"author":1,"featured_media":55298,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14120],"tags":[2,18124,17948],"class_list":["post-55297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-blog-do-edvaldo-magalhaes","tag-comeca-a-montagem-do-hospital-de-campanha-no-hmv-em-caruaru","tag-coronavirus-2"],"_links":{"self":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/55297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=55297"}],"version-history":[{"count":5,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/55297\/revisions"}],"predecessor-version":[{"id":55353,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/55297\/revisions\/55353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/media\/55298"}],"wp:attachment":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=55297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=55297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=55297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}