{"id":5442,"date":"2017-07-05T20:06:00","date_gmt":"2017-07-05T23:06:00","guid":{"rendered":"http:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/2017\/07\/05\/santander-abre-vagas-em-caruaru-e-mais\/"},"modified":"2019-02-09T01:34:16","modified_gmt":"2019-02-09T03:34:16","slug":"santander-abre-vagas-em-caruaru-e-mais","status":"publish","type":"post","link":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/2017\/07\/05\/santander-abre-vagas-em-caruaru-e-mais\/","title":{"rendered":"Santander abre vagas em Caruaru e mais 11 cidades do Nordeste"},"content":{"rendered":"<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<a href=\"https:\/\/3.bp.blogspot.com\/-zGStgL-OSGg\/WV1GjieEuoI\/AAAAAAAAY74\/T_G_b33H6u0ntnXrfP64djzRByW67SsJQCLcBGAs\/s1600\/ha%25C2%25B4vagas.jpg\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"90\" data-original-width=\"130\" height=\"276\" src=\"http:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2017\/07\/haC2B4vagas.jpg\" width=\"400\" \/><\/a><\/div>\n<div style=\"margin-bottom: .0001pt; margin: 0cm; text-align: justify;\">\n<\/div>\n<div style=\"margin-bottom: .0001pt; margin: 0cm; text-align: justify;\">\nO Santander abriu 24<br \/>\npostos de emprego para a fun\u00e7\u00e3o de Agente de Microcr\u00e9dito em 12 cidades do<br \/>\nNordeste. Buscando otimizar o processo seletivo e selecionar as pessoas com<br \/>\nperfil mais adequado, o banco optou por fazer o recrutamento de uma forma<br \/>\ninovadora. Vai utilizar o aplicativo de empregos TAQE, que capacita e recomenda<br \/>\ncandidatos para o mercado de trabalho.<\/div>\n<div style=\"margin-bottom: .0001pt; margin: 0cm; text-align: justify;\">\n<\/div>\n<div style=\"margin-bottom: .0001pt; margin: 0cm; text-align: justify;\">\nAs posi\u00e7\u00f5es s\u00e3o para<br \/>\nas cidades de Recife, Caruaru, Serra Talhada e Petrolina em Pernambuco; Caic\u00f3,<br \/>\nMossor\u00f3 e Pau dos Ferros, no Rio Grande do Norte; Macei\u00f3 e Palmeira dos \u00cdndios,<br \/>\nem Alagoas; Concei\u00e7\u00e3o do Coit\u00e9 e Senhor do Bonfim, na Bahia; Maracana\u00fa, no<br \/>\nCear\u00e1, e Sum\u00e9\/Monteiro, na Para\u00edba.<\/div>\n<div style=\"margin-bottom: .0001pt; margin: 0cm; text-align: justify;\">\n<\/div>\n<div style=\"margin-bottom: .0001pt; margin: 0cm; text-align: justify;\">\nO Agente de<br \/>\nMicrocr\u00e9dito deve ser uma pessoa que conhe\u00e7a bem a regi\u00e3o onde atuar\u00e1,<br \/>\nacompanhando e dando suporte aos empreendedores durante o contrato de<br \/>\nmicrocr\u00e9dito. \u00c9 um atendimento pessoal, que orienta o empreendedor na gest\u00e3o de<br \/>\nneg\u00f3cios e identifica\u00e7\u00e3o de oportunidades (orienta\u00e7\u00e3o financeira).<\/div>\n<div style=\"margin-bottom: .0001pt; margin: 0cm; text-align: justify;\">\n<\/div>\n<div style=\"margin-bottom: .0001pt; margin: 0cm; text-align: justify;\">\nO intuito \u00e9 buscar<br \/>\nprofissionais com garra, energia e que preferencialmente j\u00e1 tenham atuado com<br \/>\nmicrocr\u00e9dito. O aplicativo TAQE auxiliar\u00e1 o Banco nessa tarefa. Nele, depois de<br \/>\nse cadastrar com informa\u00e7\u00f5es b\u00e1sicas como nome, escolaridade e CEP, o usu\u00e1rio<br \/>\nganha acesso a testes de personalidade, compet\u00eancias, portugu\u00eas, l\u00f3gica, entre<br \/>\noutros. A cada etapa finalizada, ganha pontos e, al\u00e9m de desbloquear novas<br \/>\naulas e testes, tamb\u00e9m recebe recomenda\u00e7\u00f5es de vagas que combinam com seu<br \/>\nperfil, \u00e0s quais se candidata, dando in\u00edcio ao processo seletivo. Ap\u00f3s a<br \/>\nprimeira fase pelo aplicativo, os selecionados passar\u00e3o por entrevistas<br \/>\npresenciais com gestores e RH.<\/div>\n<div style=\"margin-bottom: .0001pt; margin: 0cm; text-align: justify;\">\n<\/div>\n<div style=\"margin-bottom: .0001pt; margin: 0cm; text-align: justify;\">\n<b>Como concorrer \u00e0s<br \/>\nvagas no Santander<\/b><\/div>\n<div style=\"margin-bottom: .0001pt; margin: 0cm; text-align: justify;\">\n<\/div>\n<p><\/p>\n<div style=\"margin: 0cm 0cm 0.0001pt; text-align: justify;\">\nPara<br \/>\nse inscrever, os interessados devem acessar o link<br \/>\nhttp:\/\/taqe.app.link\/vagasantander do navegador de seu celular e baixar o aplicativo.<br \/>\n\u00c9 necess\u00e1rio que os candidatos baixem especificamente essa vers\u00e3o, em vez de<br \/>\nfazer o download diretamente pelo Google Play ou App Store, pois somente desta<br \/>\nforma concorrer\u00e3o \u00e0s vagas oferecidas pelo banco.<\/div>\n<div style=\"margin: 0cm 0cm 0.0001pt; text-align: justify;\">\n<\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<a href=\"http:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2017\/07\/6-STR-4.jpg\" imageanchor=\"1\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" data-original-height=\"100\" data-original-width=\"570\" src=\"http:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2017\/07\/6-STR-4.jpg\" \/><\/a><\/div>\n<div style=\"margin: 0cm 0cm 0.0001pt; text-align: justify;\">\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Santander abriu 24 postos de emprego para a fun\u00e7\u00e3o de Agente de Microcr\u00e9dito em 12 cidades do Nordeste. Buscando&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2,6,7242],"class_list":["post-5442","post","type-post","status-publish","format-standard","hentry","category-sem-categoria","tag-blog-do-edvaldo-magalhaes","tag-noticias","tag-santander-abre-vagas-em-caruaru-e-mais-11-cidades-do-nordeste"],"_links":{"self":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5442"}],"version-history":[{"count":1,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5442\/revisions"}],"predecessor-version":[{"id":21737,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5442\/revisions\/21737"}],"wp:attachment":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}