{"id":5191,"date":"2017-08-02T21:10:00","date_gmt":"2017-08-03T00:10:00","guid":{"rendered":"http:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/2017\/08\/02\/resultado-da-audiencia-de-custodia-da\/"},"modified":"2019-02-09T01:37:43","modified_gmt":"2019-02-09T03:37:43","slug":"resultado-da-audiencia-de-custodia-da","status":"publish","type":"post","link":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/2017\/08\/02\/resultado-da-audiencia-de-custodia-da\/","title":{"rendered":"Resultado da Audi\u00eancia de Cust\u00f3dia da filha que matou a m\u00e3e em Caruaru"},"content":{"rendered":"<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<a href=\"https:\/\/3.bp.blogspot.com\/-fmqZOPGFpaE\/WYI-44M4ypI\/AAAAAAAAal0\/HnIin6087ZwOiO15Wz7bLz6z62LkCWsnQCLcBGAs\/s1600\/IMG-20170802-WA0134.jpg\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"540\" data-original-width=\"540\" height=\"400\" src=\"http:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2017\/08\/IMG-20170802-WA0134.jpg\" width=\"400\" \/><\/a><\/div>\n<div style=\"text-align: justify;\">\n<br \/>\nJana\u00edna Maria da Silva, de 27 anos, que matou a com golpes de faca peixeira a m\u00e3e Maria do Carmo da Silva, passou por uma Audi\u00eancia de Cust\u00f3dia, na tarde desta quarta-feira (02), e a justi\u00e7a determinou a pris\u00e3o dela em regime fechado Col\u00f4nia Penal Feminina de Bu\u00edque, onde aguardar\u00e1 julgamento.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jana\u00edna Maria da Silva, de 27 anos, que matou a com golpes de faca peixeira a m\u00e3e Maria do Carmo&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2,6806,6807,6808,13,6809],"class_list":["post-5191","post","type-post","status-publish","format-standard","hentry","category-sem-categoria","tag-blog-do-edvaldo-magalhaes","tag-colonia-penal-feminina-de-buique","tag-janaina-maria-da-silva","tag-maria-do-carmo-da-silva","tag-policial","tag-resultado-da-audiencia-de-custodia-da-filha-que-matou-a-mae-em-caruaru"],"_links":{"self":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5191"}],"version-history":[{"count":1,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5191\/revisions"}],"predecessor-version":[{"id":22687,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5191\/revisions\/22687"}],"wp:attachment":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}