{"id":38263,"date":"2019-02-11T13:59:34","date_gmt":"2019-02-11T16:59:34","guid":{"rendered":"http:\/\/blogdoedvaldomagalhaes.com.br\/?p=38263"},"modified":"2019-02-11T22:29:14","modified_gmt":"2019-02-12T01:29:14","slug":"jornalista-ricardo-boechat-morre-em-queda-de-helicoptero","status":"publish","type":"post","link":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/2019\/02\/11\/jornalista-ricardo-boechat-morre-em-queda-de-helicoptero\/","title":{"rendered":"Jornalista Ricardo Boechat morre em queda de helic\u00f3ptero"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O jornalista Ricardo Boechat, 66,&nbsp;morreu ap\u00f3s a&nbsp;queda de um helic\u00f3ptero em S\u00e3o Paulo nesta segunda-feira (11).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A informa\u00e7\u00e3o foi confirmada pela&nbsp;<strong>Folha<\/strong>. O Corpo de Bombeiros informou que duas pessoas tinham morrido&nbsp;ap\u00f3s um helic\u00f3ptero cair sobre um caminh\u00e3o em trecho do Rodoanel que d\u00e1 acesso \u00e0 rodovia Anhanguera, na zona oeste de S\u00e3o Paulo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eles seriam o piloto e o copiloto da aeronave, segundo as informa\u00e7\u00f5es preliminares da corpora\u00e7\u00e3o. A confirma\u00e7\u00e3o de que o jornalista era um dos ocupantes veio mais tarde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um caminh\u00e3o foi atingido pela aeronave. \u200bO motorista foi socorrido<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O acidente ocorreu na altura do quil\u00f4metro 7 do Rodoanel, sentido Castelo Branco, pr\u00f3ximo a um ped\u00e1gio.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A corpora\u00e7\u00e3o atende a ocorr\u00eancia com um helic\u00f3ptero e 11 viaturas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Foram feitas interdi\u00e7\u00f5es parciais nas pistas&nbsp;do Rodoanel sentido Perus \u200be da Anhanguera sentido Jundia\u00ed. A concession\u00e1ria CCR&nbsp;Rodoanel, que administra o trecho oeste do Rodoanel, informa que os motoristas t\u00eam como op\u00e7\u00e3o acessar a Anhanguera sentido S\u00e3o Paulo e pegar um retorno no quil\u00f4metro 18 para seguir sentido Jundia\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fonte: Folha S.Paulo<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"253\" src=\"http:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2019\/02\/IMG-20190211-WA0075.jpg\" alt=\"\" class=\"wp-image-38264\" srcset=\"https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2019\/02\/IMG-20190211-WA0075.jpg 400w, https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2019\/02\/IMG-20190211-WA0075-300x190.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O jornalista Ricardo Boechat, 66,&nbsp;morreu ap\u00f3s a&nbsp;queda de um helic\u00f3ptero em S\u00e3o Paulo nesta segunda-feira (11).&nbsp; A informa\u00e7\u00e3o foi confirmada&hellip;<\/p>\n","protected":false},"author":1,"featured_media":38269,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14120],"tags":[14129,3133,14126,14128,14127,2575],"class_list":["post-38263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-anhanguera","tag-corpo-de-bombeiros","tag-jornalista-ricardo-boechat-morre-em-queda-de-helicoptero","tag-perus","tag-rodoanel","tag-sao-paulo"],"_links":{"self":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/38263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=38263"}],"version-history":[{"count":2,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/38263\/revisions"}],"predecessor-version":[{"id":38270,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/38263\/revisions\/38270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/media\/38269"}],"wp:attachment":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=38263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=38263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=38263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}