{"id":115888,"date":"2025-01-16T13:52:16","date_gmt":"2025-01-16T16:52:16","guid":{"rendered":"https:\/\/blogdoedvaldomagalhaes.com.br\/?p=115888"},"modified":"2025-01-16T13:52:16","modified_gmt":"2025-01-16T16:52:16","slug":"operacao-descanso-legal-emite-mais-de-160-autuacoes-em-onibus-e-caminhoes","status":"publish","type":"post","link":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/2025\/01\/16\/operacao-descanso-legal-emite-mais-de-160-autuacoes-em-onibus-e-caminhoes\/","title":{"rendered":"Opera\u00e7\u00e3o Descanso Legal emite mais de 160 autua\u00e7\u00f5es em \u00f4nibus e caminh\u00f5es"},"content":{"rendered":"<p>Entre os dias 6 e 15 de janeiro, a Pol\u00edcia Rodovi\u00e1ria Federal (PRF) intensificou a fiscaliza\u00e7\u00e3o dos ve\u00edculos de grande porte em Pernambuco, atrav\u00e9s da Opera\u00e7\u00e3o Descanso Legal. A iniciativa teve como foco refor\u00e7ar a seguran\u00e7a vi\u00e1ria, prevenir sinistros e infra\u00e7\u00f5es envolvendo caminh\u00f5es e \u00f4nibus nas rodovias federais.<\/p>\n<p>Em dez dias, as equipes fiscalizaram 407 ve\u00edculos  de grande porte e 394 pessoas, sendo emitidas 504 autua\u00e7\u00f5es por diversas infra\u00e7\u00f5es. A fiscaliza\u00e7\u00e3o do tempo de descanso do motorista resultou em 162 autua\u00e7\u00f5es, a partir da an\u00e1lise do tac\u00f3grafo, um equipamento que registra o tempo de dire\u00e7\u00e3o, a velocidade m\u00e9dia e a dist\u00e2ncia percorrida pelo ve\u00edculo.<\/p>\n<p>O excesso de peso tamb\u00e9m foi verificado durante a opera\u00e7\u00e3o e foram emitidas 29 autua\u00e7\u00f5es pelo transporte de carga acima dos limites permitidos. Do total de motoristas abordados, 14 n\u00e3o estavam com o exame toxicol\u00f3gico em dia e tamb\u00e9m foram autuados.<\/p>\n<p>Al\u00e9m dessas, outras infra\u00e7\u00f5es como sistema de freios inoperante, pneus em mau estado de conserva\u00e7\u00e3o e falta de sinaliza\u00e7\u00e3o dos ve\u00edculos tamb\u00e9m foram observadas. A fiscaliza\u00e7\u00e3o dos ve\u00edculos de grande porte continuar\u00e1 a ser realizada em Pernambuco, com o apoio dos Grupos de Fiscaliza\u00e7\u00e3o de Tr\u00e2nsito e Transporte (GFT) da PRF.<\/p>\n<p>Lei do Descanso<\/p>\n<p>De acordo com a lei, o motorista n\u00e3o pode dirigir por mais de 5 horas e meia seguidas, ele precisa descansar por no m\u00ednimo 30 minutos. E a cada jornada de 24h, o condutor deve descansar por 11 horas.<br \/>\nSeja seguidor do Instagram do Blog pelo @blogdoedvaldomagalhaes.<br \/>\nFoto: Divulga\u00e7\u00e3o\/PRF<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre os dias 6 e 15 de janeiro, a Pol\u00edcia Rodovi\u00e1ria Federal (PRF) intensificou a fiscaliza\u00e7\u00e3o dos ve\u00edculos de grande&hellip;<\/p>\n","protected":false},"author":1,"featured_media":115889,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14121],"tags":[30592,27410,13146,28801,32497,287],"class_list":["post-115888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial","tag-blog-com-mais-seguidores","tag-blog-de-caruaru","tag-blog-edvaldo-magalhaes","tag-blog-mais-acessado","tag-operacao-descanso-legal-emite-mais-de-160-autuacoes-em-onibus-e-caminhoes","tag-prf"],"_links":{"self":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/115888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=115888"}],"version-history":[{"count":1,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/115888\/revisions"}],"predecessor-version":[{"id":115890,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/115888\/revisions\/115890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/media\/115889"}],"wp:attachment":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=115888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=115888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=115888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}