{"id":109043,"date":"2024-06-01T13:22:06","date_gmt":"2024-06-01T16:22:06","guid":{"rendered":"https:\/\/blogdoedvaldomagalhaes.com.br\/?p=109043"},"modified":"2024-06-01T13:32:50","modified_gmt":"2024-06-01T16:32:50","slug":"cartilha-para-auxiliar-mulheres-em-situacao-de-violencia-de-genero","status":"publish","type":"post","link":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/2024\/06\/01\/cartilha-para-auxiliar-mulheres-em-situacao-de-violencia-de-genero\/","title":{"rendered":"Cartilha para auxiliar mulheres em situa\u00e7\u00e3o de viol\u00eancia de g\u00eanero"},"content":{"rendered":"<p>A Secretaria de Pol\u00edticas para Mulheres de Caruaru (SPM), lan\u00e7a a cartilha \u201cDiz, Mulher\u201d para orientar e apoiar mulheres em situa\u00e7\u00e3o de viol\u00eancia dom\u00e9stica e familiar. O material chega um dia antes do in\u00edcio do S\u00e3o Jo\u00e3o de Caruaru 2024, visando a preven\u00e7\u00e3o contra a viol\u00eancia de g\u00eanero tamb\u00e9m durante as festividades juninas.<\/p>\n<p>Desenvolvida pela SPM, a cartilha \u00e9 direcionada a mulheres de todas as idades, n\u00edveis de escolaridade, classes sociais e etnias, e oferece, de forma did\u00e1tica, desde conceitos b\u00e1sicos sobre o processo de viol\u00eancia, impactos e legisla\u00e7\u00e3o, at\u00e9 o funcionamento da rede de prote\u00e7\u00e3o, atendimento e canais de den\u00fancia. No material, \u00e9 poss\u00edvel conferir tamb\u00e9m todos os servi\u00e7os oferecidos pela pasta no munic\u00edpio, incluindo a\u00e7\u00f5es de sa\u00fade e qualidade de vida, cidadania, qualifica\u00e7\u00e3o profissional e enfrentamento \u00e0 viol\u00eancia.<\/p>\n<p>\u201cA cartilha foi pensada com muita dedica\u00e7\u00e3o para conter o m\u00e1ximo de informa\u00e7\u00f5es poss\u00edveis, para que a mulher esteja munida de todos os elementos que a auxiliem a identificar a viol\u00eancia, os meios de acolhimento e den\u00fancia para quebrar o ciclo de viol\u00eancia. Lan\u00e7ar esse material durante o m\u00eas de maior circula\u00e7\u00e3o de pessoas na nossa cidade, onde o mundo olha para Caruaru, tem um significado muito grande, pois a nossa cidade tem uma rede de Enfrentamento \u00e0 Viol\u00eancia contra a Mulher unida pelo fim da viol\u00eancia de g\u00eanero\u201d, destaca Luana Marabuco, secret\u00e1ria de Pol\u00edticas para Mulheres de Caruaru.<\/p>\n<p>A Prefeitura de Caruaru reafirma seu compromisso com a prote\u00e7\u00e3o e apoio \u00e0s mulheres, e a cartilha \u201cDiz, Mulher\u201d \u00e9 mais um passo importante para garantir a seguran\u00e7a e o bem-estar das caruaruenses. O material j\u00e1 est\u00e1 dispon\u00edvel para a popula\u00e7\u00e3o atrav\u00e9s do site da prefeitura de Caruaru e no portal Conhe\u00e7a Caruaru, no link: https:\/\/conheca.caruaru.pe.gov.br\/site\/protecao-a-mulher<br \/>\nSeja seguidor do Instagram do Blog para comentar @blogdoedvaldomagalhaes<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-109046 alignnone size-full\" src=\"https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2024\/06\/img-20240530-wa00551419741233068938196.jpg\" width=\"900\" height=\"1600\" srcset=\"https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2024\/06\/img-20240530-wa00551419741233068938196.jpg 900w, https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2024\/06\/img-20240530-wa00551419741233068938196-169x300.jpg 169w, https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2024\/06\/img-20240530-wa00551419741233068938196-576x1024.jpg 576w, https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2024\/06\/img-20240530-wa00551419741233068938196-768x1365.jpg 768w, https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2024\/06\/img-20240530-wa00551419741233068938196-864x1536.jpg 864w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2024\/06\/img-20240531-wa04116537629367828260662.jpg\" class=\"wp-image-109049 alignnone size-full\" width=\"1284\" height=\"1595\" srcset=\"https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2024\/06\/img-20240531-wa04116537629367828260662.jpg 1284w, https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2024\/06\/img-20240531-wa04116537629367828260662-242x300.jpg 242w, https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2024\/06\/img-20240531-wa04116537629367828260662-824x1024.jpg 824w, https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2024\/06\/img-20240531-wa04116537629367828260662-768x954.jpg 768w, https:\/\/blogdoedvaldomagalhaes.com.br\/wp-content\/uploads\/2024\/06\/img-20240531-wa04116537629367828260662-1237x1536.jpg 1237w\" sizes=\"auto, (max-width: 1284px) 100vw, 1284px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Pol\u00edticas para Mulheres de Caruaru (SPM), lan\u00e7a a cartilha \u201cDiz, Mulher\u201d para orientar e apoiar mulheres em&hellip;<\/p>\n","protected":false},"author":1,"featured_media":109044,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14120],"tags":[30592,2,28801,30691],"class_list":["post-109043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-blog-com-mais-seguidores","tag-blog-do-edvaldo-magalhaes","tag-blog-mais-acessado","tag-cartilha-para-auxiliar-mulheres-em-situacao-de-violencia-de-genero"],"_links":{"self":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/109043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=109043"}],"version-history":[{"count":3,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/109043\/revisions"}],"predecessor-version":[{"id":109050,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/109043\/revisions\/109050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/media\/109044"}],"wp:attachment":[{"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=109043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=109043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoedvaldomagalhaes.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=109043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}